{"id":1512,"date":"2023-07-31T10:13:16","date_gmt":"2023-07-31T08:13:16","guid":{"rendered":"http:\/\/www.athol.es\/?page_id=1512"},"modified":"2025-12-26T10:40:01","modified_gmt":"2025-12-26T09:40:01","slug":"nave-logistica-en-alquiler-madrid","status":"publish","type":"page","link":"https:\/\/www.athol.es\/en\/landing\/logistic-warehouses-for-renting-madrid\/","title":{"rendered":"Logistic Building for renting - Madrid"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1512\" class=\"elementor elementor-1512\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c132306 elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"c132306\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ea2a30\" data-id=\"3ea2a30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fa1b589 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"fa1b589\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-11029ff8\" data-id=\"11029ff8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-925f25c elementor-widget__width-auto ha-has-bg-overlay elementor-widget elementor-widget-image\" data-id=\"925f25c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"89\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/2023\/09\/athol_header-300x89.png\" class=\"attachment-medium size-medium wp-image-3183\" alt=\"\" srcset=\"https:\/\/www.athol.es\/wp-content\/uploads\/2023\/09\/athol_header-300x89.png 300w, https:\/\/www.athol.es\/wp-content\/uploads\/2023\/09\/athol_header.png 766w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e7443e9 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"e7443e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:300,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a56f2f2\" data-id=\"a56f2f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57adba0 elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-image\" data-id=\"57adba0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"282\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/2023\/07\/LOGO_BREEAM_HERRADURA-1-300x282.png\" class=\"attachment-medium size-medium wp-image-1514\" alt=\"\" srcset=\"https:\/\/www.athol.es\/wp-content\/uploads\/2023\/07\/LOGO_BREEAM_HERRADURA-1-300x282.png 300w, https:\/\/www.athol.es\/wp-content\/uploads\/2023\/07\/LOGO_BREEAM_HERRADURA-1.png 536w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8e1d8a8 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8e1d8a8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-df6b2e4\" data-id=\"df6b2e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17e4688 elementor-widget-tablet__width-initial elementor-widget-mobile__width-auto elementor-widget__width-initial titulo-landing elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"17e4688\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Edificio log\u00edstico <br>en alquiler en Madrid<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-466d6b1 elementor-widget__width-auto subtit-landing elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"466d6b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCTRA N-A1, KM 31,5. P.I SUR,\nSAN AGUST\u00cdN DEL GUADALIX\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aac40f7\" data-id=\"aac40f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49095e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49095e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f05078a\" data-id=\"f05078a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aeb0dbb elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"aeb0dbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">De superficie<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"15610\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> m\u00b2<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e013d57\" data-id=\"e013d57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2301f4d elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"2301f4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Edificio log\u00edstico<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"13710\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> m\u00b2<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-554a332\" data-id=\"554a332\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f298e50 elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"f298e50\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Oficinas y vestuarios<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1900\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> m\u00b2<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-73f54fa\" data-id=\"73f54fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c906d29 elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"c906d29\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">m\u00b2\/mes<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"2.75\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"> \u20ac<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-114c934 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"114c934\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da29c8d\" data-id=\"da29c8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4a5e6a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a5e6a7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20bbab6\" data-id=\"20bbab6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1324717\" data-id=\"1324717\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dcb947 elementor-align-start elementor-widget__width-auto elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"7dcb947\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">150 m lineales de nueva fachada<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb82a3 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"2eb82a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-road\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00e1cil acceso a la A1 desde la v\u00eda de servicio.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-city\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A 30 minutos de Madrid.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plane-departure\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A 15 minutos del aeropuerto Madrid-Barajas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8f6a0c elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8f6a0c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b69200\" data-id=\"2b69200\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4ad06c elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4ad06c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15dad45\" data-id=\"15dad45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ef368f elementor-widget elementor-widget-image\" data-id=\"3ef368f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"791\" height=\"683\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/2023\/11\/map_3_mobile_v2.png\" class=\"attachment-full size-full wp-image-3913\" alt=\"\" srcset=\"https:\/\/www.athol.es\/wp-content\/uploads\/2023\/11\/map_3_mobile_v2.png 791w, https:\/\/www.athol.es\/wp-content\/uploads\/2023\/11\/map_3_mobile_v2-300x259.png 300w, https:\/\/www.athol.es\/wp-content\/uploads\/2023\/11\/map_3_mobile_v2-768x663.png 768w\" sizes=\"(max-width: 791px) 100vw, 791px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e46513c\" data-id=\"e46513c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0eda29 elementor-align-start elementor-widget__width-auto elementor-widget-tablet__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"d0eda29\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">150m lineales de nueva fachada<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f47235 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"9f47235\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-road\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">F\u00e1cil acceso a la A1 desde la v\u00eda de servicio.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-city\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A 30 minutos de Madrid.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plane-departure\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A 15 minutos del aeropuerto Madrid-Barajas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c3f8c55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3f8c55\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36e3161\" data-id=\"36e3161\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35ec9cd6 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"35ec9cd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Edificio para distribuci\u00f3n<\/b>, <b>almacenamiento y log\u00edstica<\/b>\u00a0con <b>Sello BREEAM,<\/b> situado en el Pol\u00edgono Industrial Sur\u00a0<\/p><p><span style=\"letter-spacing: 0px; background-color: var( --e-global-color-16e9549 );\">del municipio de San Agust\u00edn del Guadalix (Madrid) en la Nacional A-1 KM 31,5.<\/span><\/p><p>Con acceso directo desde la autov\u00eda nacional A-1.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e5b16d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e5b16d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a69bb1\" data-id=\"4a69bb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9b7ec6 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"a9b7ec6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"WhatsApp Image 2024-04-10 at 19.42.58 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc2NSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL1doYXRzQXBwLUltYWdlLTIwMjQtMDQtMTAtYXQtMTkuNDIuNTgtMS5qcGVnIiwic2xpZGVzaG93IjoiYTliN2VjNiJ9\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-10-at-19.42.58-1.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/WhatsApp-Image-2024-04-10-at-19.42.58-1-qp7izxaa6kvp8c4jocunkv6o7l84k9wn1kjvfzacvs.jpeg\" alt=\"WhatsApp Image 2024-04-10 at 19.42.58 (1)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTAwNywidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDVcL2ltYWdlMDA2LmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/05\/image006.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/image006-qp7j49bhp2tarltwd8aq2rt6tjv22142z0uh3wv06w.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc2OCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MjMwNF8wMjMxX0QtRURJVEFEQS1zY2FsZWQuanBlZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405092304_0231_D-EDITADA-scaled.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405092304_0231_D-EDITADA-scaled-qp7iyzg3cjldmdhp5y8333q2tpuwv66awx2e60oj3s.jpeg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc4MywidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MjM1M18wMjM2X0QuanBnIiwic2xpZGVzaG93IjoiYTliN2VjNiJ9\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405092353_0236_D.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405092353_0236_D-qp7j1synungcg9e8p63ske3uzbyjyhdbavitzwi0fs.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTAwOCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDVcL2ltYWdlMDA5LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiJhOWI3ZWM2In0%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/05\/image009-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/image009-scaled-qp7j49bhp2tarltwd8aq2rt6tjv22142z0uh3wv06w.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc3MSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5Mjg0NV8wMjUzX0QtRURJVEFEQS1zY2FsZWQuanBlZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405092845_0253_D-EDITADA-scaled.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405092845_0253_D-EDITADA-scaled-qp7iz1brq7ny9leyuz1c83900hlnakdrl6dd4klqrc.jpeg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc3MCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MjgxNV8wMjUwX0QtRURJVEFEQS1zY2FsZWQuanBlZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405092815_0250_D-EDITADA-scaled.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405092815_0250_D-EDITADA-scaled-qp7j2n1hxclirs6jtj3us6ilznuassoq30edcr9ewo.jpeg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc3NywidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MTMzMl8wMjA3X0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405091332_0207_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405091332_0207_D-scaled-qp7j35u9q1b97zf8rr8e61rtvd9n2qrctlg2yahjg8.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc3OCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MTk1MV8wMjIyX0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405091951_0222_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405091951_0222_D-scaled-qp7iymacov3d3u0tasjb471mibnrveq273xlg581iw.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc4MiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MjE1MV8wMjI4X0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405092151_0228_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405092151_0228_D-scaled-qp7j29vr9o3i98pnydf2t9u5o9n5t18hd79kmvsxbs.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc4MSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MjE0MV8wMjI3X0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405092141_0227_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405092141_0227_D-scaled-qp7j2n1hxclirs6jtj3us6ilznuassoq30edcr9ewo.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc4MCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MjExN18wMjI1X0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405092117_0225_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405092117_0225_D-scaled-qp7iz534hjt3k19i90nui2aue1345csoxozb1og62g.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc3OSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MjA1MF8wMjI0X0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405092050_0224_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405092050_0224_D-scaled-qp7j2ybk7d0yn3q5znzdm3o54aapd5xi4k8742sou0.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"ef7ab14b-b6dd-412b-940a-345c5e1f6779\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTIyNCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDZcL2VmN2FiMTRiLWI2ZGQtNDEyYi05NDBhLTM0NWM1ZTFmNjc3OS5qcGciLCJzbGlkZXNob3ciOiJhOWI3ZWM2In0%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/06\/ef7ab14b-b6dd-412b-940a-345c5e1f6779.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/ef7ab14b-b6dd-412b-940a-345c5e1f6779-qpgiyjofgq4pnzim5l80pue3oln9j9ph66ut3702bc.jpg\" alt=\"ef7ab14b-b6dd-412b-940a-345c5e1f6779\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDc4NiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDRcL0RKSV8yMDI0MDQwNTA5MzMzOV8wMjYxX0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/04\/DJI_20240405093339_0261_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240405093339_0261_D-scaled-qp7j0rd49a0vjuwuspupsnlf7x3vel81tpfesu1rco.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTI4MSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL0RKSV8yMDI0MDcxNzEyMjMxMl8wNDI0X0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/10\/DJI_20240717122312_0424_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240717122312_0424_D-scaled-quywcn2bbl36bnt7kp3fijym1nao14k640fch6yfug.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTI4MywidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL0RKSV8yMDI0MDcxNzEyMjM1MF8wNDI4X0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/10\/DJI_20240717122350_0428_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240717122350_0428_D-scaled-quyweaa5a5c8n3f6ywoxdn0ngx6si239c5ixpmimyg.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTI4MCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL0RKSV8yMDI0MDcxNzEyMjMwOV8wNDIzX0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/10\/DJI_20240717122309_0423_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240717122309_0423_D-scaled-quywbwqu0835akvfudpvkqlpeuwe1lnooe5r1g1goo.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTI4MiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL0RKSV8yMDI0MDcxNzEyMjMxNV8wNDI1X0Qtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/10\/DJI_20240717122315_0425_D-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/DJI_20240717122315_0425_D-scaled-quywdcfyg41x14scgi2cvvk231tksycx7i1gfnwt6g.jpg\" alt=\"default\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"WhatsApp_Image_2024-03-21_at_12.20.02_(4)[1]\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTI3OSwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1doYXRzQXBwX0ltYWdlXzIwMjQtMDMtMjFfYXRfMTIuMjAuMDJfNDEuanBlZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/10\/WhatsApp_Image_2024-03-21_at_12.20.02_41.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/WhatsApp_Image_2024-03-21_at_12.20.02_41-quyw6cj7kih2lmy9bh6cbn4ivsb7i2kuwv7btiabi0.jpeg\" alt=\"WhatsApp_Image_2024-03-21_at_12.20.02_(4)[1]\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"WhatsApp_Image_2024-03-21_at_12.20.02_(5)[1]\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTI3OCwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL1doYXRzQXBwX0ltYWdlXzIwMjQtMDMtMjFfYXRfMTIuMjAuMDJfNTEuanBlZyIsInNsaWRlc2hvdyI6ImE5YjdlYzYifQ%3D%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/10\/WhatsApp_Image_2024-03-21_at_12.20.02_51.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/WhatsApp_Image_2024-03-21_at_12.20.02_51-quyw3mrztqr926w96ax54bsl3pp19jsrvfctwqb9h4.jpeg\" alt=\"WhatsApp_Image_2024-03-21_at_12.20.02_(5)[1]\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 22\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9b7ec6\" data-elementor-lightbox-title=\"default\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTI3NiwidXJsIjoiaHR0cHM6XC9cL3d3dy5hdGhvbC5lc1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTBcL2ltYWdlMDA4LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiJhOWI3ZWM2In0%3D\" href=\"https:\/\/www.athol.es\/wp-content\/uploads\/2024\/10\/image008-scaled.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/image008-scaled-quyw2cpwiv079ar5n90f85ezzu01sdpxd3e1e67jy0.jpg\" alt=\"default\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0f487f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0f487f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf390bc\" data-id=\"cf390bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80dd129 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"80dd129\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CARACTER\u00cdSTICAS PRINCIPALES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc3d493 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fc3d493\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-66c5c92\" data-id=\"66c5c92\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e6ee796\" data-id=\"7e6ee796\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10f8f6bc elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"10f8f6bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">150m lineales de nueva fachada a la A-1.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">T\u00f3tem privativo.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">29 muelles de carga con plataforma nivelada para furgonetas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 muelles y 2 rampas de acceso para trailers.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">6 montacargas de gran tama\u00f1o que conectan las 2 plantas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nave de distribuci\u00f3n, con Sello BREEAM Good, de 2 plantas con accesos diferenciados desde planta calle. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Estructura y solera de hormig\u00f3n armado.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Oficinas acondicionadas con suelo t\u00e9cnico y mamparas. Posible sede corporativa: sala de reuniones, sal\u00f3n de actos (100 pax), zona de archivo y office corner. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">60 plazas de parking.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Recinto perimetral cerrado con control de acceso.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nuevo asfaltado exterior.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-lightbulb\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Iluminaci\u00f3n Led.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-wheelchair\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accesibilidad para personas con movilidad reducida. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d60d125 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d60d125\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-122e38ae\" data-id=\"122e38ae\" data-element_type=\"column\" data-e-type=\"column\" id=\"form\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6629cecf elementor-widget elementor-widget-heading\" data-id=\"6629cecf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solicita informaci\u00f3n ahora<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b65184 elementor-widget__width-auto elementor-widget elementor-widget-ha-cf7 happy-addon ha-cf7\" data-id=\"0b65184\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"form_land\" data-widget_type=\"ha-cf7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4918-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"4918\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1512#wpcf7-f4918-o1\" method=\"post\" class=\"wpcf7-form init ha-cf7-form\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4918\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4918-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"nombre_land\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"apellidos_land\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apellidos\" value=\"\" type=\"text\" name=\"surname\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" id=\"tel_land\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"mail\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"mail_land\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu email\" value=\"\" type=\"email\" name=\"mail\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance\" value=\"1\" id=\"privacy_land\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Acepto la pol\u00edtica de privacidad*<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<div class=\"color-white\">\n\t<div class=\"_html-code\">\n\t\t<p>Ver <a href=\"\/politica-de-privacidad\/\">Pol\u00edtica de Privacidad<\/a>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" id=\"submit_land\" type=\"submit\" value=\"SOLICITAR INFORMACI\u00d3N\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c21fbf1\" data-id=\"2c21fbf1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40c8154e ha-has-bg-overlay elementor-widget elementor-widget-spacer\" data-id=\"40c8154e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3fd0a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3fd0a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23a731fb\" data-id=\"23a731fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bde53ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bde53ad\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-34aa16e\" data-id=\"34aa16e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b700244 elementor-widget elementor-widget-image\" data-id=\"1b700244\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"73\" height=\"17\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/2023\/07\/logo_barra_dorado.svg\" class=\"attachment-large size-large wp-image-1692\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6837152d elementor-widget elementor-widget-heading\" data-id=\"6837152d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-small\">International Commercial Real Estate Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2725311\" data-id=\"2725311\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a12df7 elementor-widget__width-inherit elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"6a12df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contacta con nosotros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-34eaeda9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34eaeda9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-957d69e elementor-hidden-mobile\" data-id=\"957d69e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c03e8c elementor-widget elementor-widget-heading\" data-id=\"6c03e8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"color: var( --e-global-color-accent );font-size: 16px;letter-spacing: 0.3px\">Madrid | Palma de Mallorca | Washington DC<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56e16f6c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"56e16f6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36bb503 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"36bb503\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Calle Hermosilla 21, 1\u00ba izq.<br>28001 Madrid, Espa\u00f1a<\/p>\n<p>Tel: <a style=\"color: #ffffff;\" href=\"tel:+34910623664\">(+34) 91<\/a>7 443 159<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5197f19 elementor-widget elementor-widget-text-editor\" data-id=\"5197f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/athol.es\" style=\"color: #fff\" target=\"_blank\" rel=\"noopener\"><b>athol.es<\/b><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e490a32 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"6e490a32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/company\/atholasset\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21a227f4 elementor-align-center elementor-widget__width-auto elementor-fixed boton_flotante elementor-invisible elementor-widget elementor-widget-button\" data-id=\"21a227f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-499b093f elementor-invisible\" data-id=\"499b093f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c91d61 elementor-widget__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"4c91d61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contacta con nosotros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-791c0a73 elementor-widget elementor-widget-image\" data-id=\"791c0a73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/1681223564731-1-e1691756979499-qp7j961bh7hdgbhvrx0fnxfnooq7jwo7qafm2xz3uo.jpg\" title=\"1681223564731.jpg\" alt=\"1681223564731.jpg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-112d7e37 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"112d7e37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">Nuria Calder\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53a01114 elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"53a01114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"tel:+34618613844\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+34 618 613 844<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aca1e7d elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"4aca1e7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"mailto:ncalderon@athol.es\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ncalderon@athol.es<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4cc63e0c elementor-invisible\" data-id=\"4cc63e0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18de96db elementor-widget elementor-widget-image\" data-id=\"18de96db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.athol.es\/wp-content\/uploads\/elementor\/thumbs\/1521485547490-1-qp7j7ln035c63prsx8mtibo01kg6q2gbijahacaq80.jpg\" title=\"1521485547490.jpg\" alt=\"1521485547490.jpg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11a4785d elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"11a4785d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Meriem Lazar<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb2b262 elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"bb2b262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"tel:+34680198315\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+34 680 198 315<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73d7ea3a elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-button\" data-id=\"73d7ea3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"mailto:mlazar@athol.es\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">mlazar@athol.es<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f39617c elementor-hidden-desktop elementor-hidden-tablet\" data-id=\"f39617c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-355f22e elementor-widget elementor-widget-heading\" data-id=\"355f22e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Madrid<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ffb8c9 elementor-widget elementor-widget-heading\" data-id=\"8ffb8c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mallorca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9f0a20 elementor-widget elementor-widget-heading\" data-id=\"b9f0a20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Washington<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4f8c5e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c4f8c5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef62752 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"ef62752\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Calle Vel\u00e1zquez, 34, Planta 7<br>28001 &#8211; Madrid&nbsp;<\/p>\n<p>Tel: <a style=\"color: #ffffff;\" href=\"tel:+34910623664\">(+34) 910 623 664<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-011e3a5 elementor-widget elementor-widget-text-editor\" data-id=\"011e3a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/athol.es\" style=\"color: #fff\" target=\"_blank\" rel=\"noopener\"><b>athol.es<\/b><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142a9ff elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"142a9ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.linkedin.com\/company\/atholasset\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6e64ba elementor-align-center elementor-widget__width-auto elementor-fixed elementor-invisible elementor-widget elementor-widget-button\" data-id=\"c6e64ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af231e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af231e3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e557e0e\" data-id=\"e557e0e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c0b538 elementor-widget elementor-widget-text-editor\" data-id=\"6c0b538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.athol.es\/condiciones-de-uso\/\">Condiciones de uso<\/a> &#8211; <a href=\"https:\/\/www.athol.es\/politica-de-privacidad\/\">Pol\u00edtica de privacidad<\/a> &#8211; <a href=\"https:\/\/www.athol.es\/politica-de-cookies\/\">Pol\u00edtica de Cookies<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Edificio log\u00edstico en alquiler en Madrid CTRA N-A1, KM 31,5. P.I SUR, SAN AGUST\u00cdN DEL GUADALIX De superficie 0 m\u00b2 Edificio log\u00edstico 0 m\u00b2 Oficinas y vestuarios 0 m\u00b2 m\u00b2\/mes 0 \u20ac 150 m lineales de nueva fachada F\u00e1cil acceso a la A1 desde la v\u00eda de servicio. A 30 minutos de Madrid. A 15 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6764,"parent":1551,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1512","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/pages\/1512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/comments?post=1512"}],"version-history":[{"count":0,"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/pages\/1512\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/pages\/1551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/media\/6764"}],"wp:attachment":[{"href":"https:\/\/www.athol.es\/en\/wp-json\/wp\/v2\/media?parent=1512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}